{"id":11176,"date":"2023-12-21T21:55:43","date_gmt":"2023-12-21T21:55:43","guid":{"rendered":"https:\/\/iestrevenque.es\/sitio\/?p=11176"},"modified":"2023-12-21T21:59:57","modified_gmt":"2023-12-21T21:59:57","slug":"siguiendo-la-ruta-del-agua-en-el-albaicin","status":"publish","type":"post","link":"https:\/\/iestrevenque.es\/sitio\/2023\/12\/21\/siguiendo-la-ruta-del-agua-en-el-albaicin\/","title":{"rendered":"SIGUIENDO LA RUTA DEL AGUA EN EL ALBAIC\u00cdN"},"content":{"rendered":"<p style=\"text-align: justify\">Este mi\u00e9rcoles y jueves el alumnado de 1\u00b0 de bachillerato ha seguido la ruta de los aljibes del Albaic\u00edn. Una actividad organizada por el departamento de matem\u00e1ticas en la que han podido conocer la historia y los usos de estas espectaculares obras de ingenier\u00eda aprendiendo las diferencias entre acequias, acueductos y sifones para llevar el agua a las cotas m\u00e1s altas. Han visitado los aljibes de San Crist\u00f3bal, de San Bartolom\u00e9, de La Vieja, de San Luis, del Salvador, de Polo, del Carmen y del Rey. Los aljibes son construcciones realizadas en la \u00e9poca \u00e1rabe de Granada que serv\u00edan para la acumulaci\u00f3n y reparto del agua en la ciudad. En la actualidad existen un total de 27 aljibes, que datan en su mayor\u00eda de \u00e9poca isl\u00e1mica, y que estuvieron en uso hasta la mitad del siglo XX, lo que ha hecho que hayan podido conservarse hasta nuestros d\u00edas.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-11178\" src=\"https:\/\/i0.wp.com\/iestrevenque.es\/sitio\/wp-content\/uploads\/2023\/12\/ca6674b0-fd5a-4c86-834f-d92c9dfc79a4.jpeg?resize=300%2C300&#038;ssl=1\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/i0.wp.com\/iestrevenque.es\/sitio\/wp-content\/uploads\/2023\/12\/ca6674b0-fd5a-4c86-834f-d92c9dfc79a4.jpeg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/iestrevenque.es\/sitio\/wp-content\/uploads\/2023\/12\/ca6674b0-fd5a-4c86-834f-d92c9dfc79a4.jpeg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/iestrevenque.es\/sitio\/wp-content\/uploads\/2023\/12\/ca6674b0-fd5a-4c86-834f-d92c9dfc79a4.jpeg?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/iestrevenque.es\/sitio\/wp-content\/uploads\/2023\/12\/ca6674b0-fd5a-4c86-834f-d92c9dfc79a4.jpeg?resize=660%2C660&amp;ssl=1 660w, https:\/\/i0.wp.com\/iestrevenque.es\/sitio\/wp-content\/uploads\/2023\/12\/ca6674b0-fd5a-4c86-834f-d92c9dfc79a4.jpeg?w=1024&amp;ssl=1 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-11179\" src=\"https:\/\/i0.wp.com\/iestrevenque.es\/sitio\/wp-content\/uploads\/2023\/12\/IMG_7917.jpeg?resize=300%2C300&#038;ssl=1\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/i0.wp.com\/iestrevenque.es\/sitio\/wp-content\/uploads\/2023\/12\/IMG_7917.jpeg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/iestrevenque.es\/sitio\/wp-content\/uploads\/2023\/12\/IMG_7917.jpeg?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/iestrevenque.es\/sitio\/wp-content\/uploads\/2023\/12\/IMG_7917.jpeg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/iestrevenque.es\/sitio\/wp-content\/uploads\/2023\/12\/IMG_7917.jpeg?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/iestrevenque.es\/sitio\/wp-content\/uploads\/2023\/12\/IMG_7917.jpeg?resize=1536%2C1536&amp;ssl=1 1536w, https:\/\/i0.wp.com\/iestrevenque.es\/sitio\/wp-content\/uploads\/2023\/12\/IMG_7917.jpeg?resize=660%2C660&amp;ssl=1 660w, https:\/\/i0.wp.com\/iestrevenque.es\/sitio\/wp-content\/uploads\/2023\/12\/IMG_7917.jpeg?w=2048&amp;ssl=1 2048w, https:\/\/i0.wp.com\/iestrevenque.es\/sitio\/wp-content\/uploads\/2023\/12\/IMG_7917.jpeg?w=1330&amp;ssl=1 1330w, https:\/\/i0.wp.com\/iestrevenque.es\/sitio\/wp-content\/uploads\/2023\/12\/IMG_7917.jpeg?w=1995&amp;ssl=1 1995w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><iframe loading=\"lazy\"  id=\"_ytid_11871\"  width=\"665\" height=\"374\"  data-origwidth=\"665\" data-origheight=\"374\" src=\"https:\/\/www.youtube.com\/embed\/yOEV6xU5Cmg?enablejsapi=1&autoplay=0&cc_load_policy=0&cc_lang_pref=&iv_load_policy=1&loop=0&rel=1&fs=1&playsinline=0&autohide=2&theme=dark&color=red&controls=1&disablekb=0&\" class=\"__youtube_prefs__  no-lazyload\" title=\"YouTube player\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe><br \/>\n<iframe loading=\"lazy\"  id=\"_ytid_72324\"  width=\"665\" height=\"374\"  data-origwidth=\"665\" data-origheight=\"374\" src=\"https:\/\/www.youtube.com\/embed\/SKqg4fOea2w?enablejsapi=1&autoplay=0&cc_load_policy=0&cc_lang_pref=&iv_load_policy=1&loop=0&rel=1&fs=1&playsinline=0&autohide=2&theme=dark&color=red&controls=1&disablekb=0&\" class=\"__youtube_prefs__  no-lazyload\" title=\"YouTube player\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este mi\u00e9rcoles y jueves el alumnado de 1\u00b0 de bachillerato ha seguido la ruta de los aljibes del Albaic\u00edn. Una actividad organizada por el departamento de matem\u00e1ticas en la que han podido conocer la historia y los usos de estas espectaculares obras de ingenier\u00eda aprendiendo las diferencias entre acequias, acueductos y sifones para llevar el\u2026 <span class=\"read-more\"><a href=\"https:\/\/iestrevenque.es\/sitio\/2023\/12\/21\/siguiendo-la-ruta-del-agua-en-el-albaicin\/\">Leer m\u00e1s &raquo;<\/a><\/span><\/p>\n","protected":false},"author":3,"featured_media":11180,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-11176","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-extraescolares-y-complementarias"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/iestrevenque.es\/sitio\/wp-content\/uploads\/2023\/12\/IMG_3981.jpeg?fit=470%2C313&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pa47Ce-2Ug","_links":{"self":[{"href":"https:\/\/iestrevenque.es\/sitio\/wp-json\/wp\/v2\/posts\/11176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iestrevenque.es\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iestrevenque.es\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iestrevenque.es\/sitio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/iestrevenque.es\/sitio\/wp-json\/wp\/v2\/comments?post=11176"}],"version-history":[{"count":6,"href":"https:\/\/iestrevenque.es\/sitio\/wp-json\/wp\/v2\/posts\/11176\/revisions"}],"predecessor-version":[{"id":11185,"href":"https:\/\/iestrevenque.es\/sitio\/wp-json\/wp\/v2\/posts\/11176\/revisions\/11185"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iestrevenque.es\/sitio\/wp-json\/wp\/v2\/media\/11180"}],"wp:attachment":[{"href":"https:\/\/iestrevenque.es\/sitio\/wp-json\/wp\/v2\/media?parent=11176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iestrevenque.es\/sitio\/wp-json\/wp\/v2\/categories?post=11176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iestrevenque.es\/sitio\/wp-json\/wp\/v2\/tags?post=11176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}