{"id":1651,"date":"2019-02-08T20:57:19","date_gmt":"2019-02-08T20:57:19","guid":{"rendered":"http:\/\/iestrevenque.es\/sitio\/?p=1651"},"modified":"2019-02-08T20:57:19","modified_gmt":"2019-02-08T20:57:19","slug":"visitando-el-teatro-de-la-maestranza-de-sevilla-musica-y-opera-tras-el-telon","status":"publish","type":"post","link":"https:\/\/iestrevenque.es\/sitio\/2019\/02\/08\/visitando-el-teatro-de-la-maestranza-de-sevilla-musica-y-opera-tras-el-telon\/","title":{"rendered":"VISITANDO EL TEATRO DE LA MAESTRANZA DE SEVILLA: M\u00fasica y \u00f3pera tras el tel\u00f3n"},"content":{"rendered":"<p>El alumnado de Literatura Universal de&nbsp; 1\u00ba de Bachillerato&nbsp; A y C&nbsp; ha realizado un tour por el interior del teatro disfrutando de los escenarios de la zarzuela que se representa en estos d\u00edas, La Tabernera del Puerto de Pablo Soroz\u00e1bal. Este recorrido&nbsp; incluye contenidos expositivos y audiovisuales combinados con explicaciones&nbsp; que les ha permitido conocer los secretos de funcionamiento del Teatro, y descubrir las zonas de trabajo&nbsp; ocultas al p\u00fablico: sala de maquillaje y peluquer\u00eda, sala de utiler\u00eda,&nbsp; maquinaria que eleva verticalmente el escenario, sala de ensayo del Coro de la Asociaci\u00f3n de Amigos del Teatro de la Maestranza,&#8230;<\/p>\nngg_shortcode_0_placeholder\n","protected":false},"excerpt":{"rendered":"<p>El alumnado de Literatura Universal de&nbsp; 1\u00ba de Bachillerato&nbsp; A y C&nbsp; ha realizado un tour por el interior del teatro disfrutando de los escenarios de la zarzuela que se representa en estos d\u00edas, La Tabernera del Puerto de Pablo Soroz\u00e1bal. Este recorrido&nbsp; incluye contenidos expositivos y audiovisuales combinados con explicaciones&nbsp; que les ha permitido\u2026 <span class=\"read-more\"><a href=\"https:\/\/iestrevenque.es\/sitio\/2019\/02\/08\/visitando-el-teatro-de-la-maestranza-de-sevilla-musica-y-opera-tras-el-telon\/\">Leer m\u00e1s &raquo;<\/a><\/span><\/p>\n","protected":false},"author":3,"featured_media":1676,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[9],"tags":[],"class_list":["post-1651","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-extraescolares-y-complementarias"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pa47Ce-qD","jetpack_featured_media_url":"https:\/\/i0.wp.com\/iestrevenque.es\/sitio\/wp-content\/uploads\/2019\/02\/adjunto_67.jpg?fit=477%2C353&ssl=1","_links":{"self":[{"href":"https:\/\/iestrevenque.es\/sitio\/wp-json\/wp\/v2\/posts\/1651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iestrevenque.es\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iestrevenque.es\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iestrevenque.es\/sitio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/iestrevenque.es\/sitio\/wp-json\/wp\/v2\/comments?post=1651"}],"version-history":[{"count":4,"href":"https:\/\/iestrevenque.es\/sitio\/wp-json\/wp\/v2\/posts\/1651\/revisions"}],"predecessor-version":[{"id":1678,"href":"https:\/\/iestrevenque.es\/sitio\/wp-json\/wp\/v2\/posts\/1651\/revisions\/1678"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iestrevenque.es\/sitio\/wp-json\/wp\/v2\/media\/1676"}],"wp:attachment":[{"href":"https:\/\/iestrevenque.es\/sitio\/wp-json\/wp\/v2\/media?parent=1651"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iestrevenque.es\/sitio\/wp-json\/wp\/v2\/categories?post=1651"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iestrevenque.es\/sitio\/wp-json\/wp\/v2\/tags?post=1651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}