{"id":3966,"date":"2020-01-22T19:12:32","date_gmt":"2020-01-22T19:12:32","guid":{"rendered":"http:\/\/iestrevenque.es\/sitio\/?p=3966"},"modified":"2020-01-22T19:12:32","modified_gmt":"2020-01-22T19:12:32","slug":"monumai-fusion-entre-historia-del-arte-matematica-e-inteligencia-artificial","status":"publish","type":"post","link":"https:\/\/iestrevenque.es\/sitio\/2020\/01\/22\/monumai-fusion-entre-historia-del-arte-matematica-e-inteligencia-artificial\/","title":{"rendered":"MONUMAI: FUSI\u00d3N ENTRE HISTORIA DEL ARTE, MATEM\u00c1TICA E INTELIGENCIA ARTIFICIAL"},"content":{"rendered":"<p style=\"text-align: justify\">El alumnado de 2\u00ba de Bachillerato y de 1\u00ba bachillerato de rob\u00f3tica y electrotecnia&nbsp; ha descubierto hoy que es MonuMAI,&nbsp; un proyecto de ciencia ciudadana de la Fundaci\u00f3n Descubre y la Universidad de Granada que ofrece la oportunidad de acercarnos a los grandes estilos art\u00edsticos de la Andaluc\u00eda Medieval y de la Edad Moderna aunando patrimonio, matem\u00e1ticas e inteligencia artificial.<\/p>\n<p style=\"text-align: justify\">Los profesores de la UGR Francisco Herrera, \u00c1lvaro Mart\u00ednez y Policarpo Cruz han explicado el funcionamiento de esta app desde las tres \u00e1reas que confluyen en ella.&nbsp;<\/p>\n<p style=\"text-align: justify\">La aplicaci\u00f3n permite identificar elementos art\u00edsticos en fotograf\u00edas de monumentos a trav\u00e9s de las matem\u00e1ticas y la inteligencia artificial.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1496\" src=\"https:\/\/i0.wp.com\/iestrevenque.es\/sitio\/wp-content\/uploads\/2019\/01\/750x750bb.jpeg?resize=169%2C300&#038;ssl=1\" alt=\"\" width=\"169\" height=\"300\"><\/p>\nngg_shortcode_0_placeholder\n","protected":false},"excerpt":{"rendered":"<p>El alumnado de 2\u00ba de Bachillerato y de 1\u00ba bachillerato de rob\u00f3tica y electrotecnia&nbsp; ha descubierto hoy que es MonuMAI,&nbsp; un proyecto de ciencia ciudadana de la Fundaci\u00f3n Descubre y la Universidad de Granada que ofrece la oportunidad de acercarnos a los grandes estilos art\u00edsticos de la Andaluc\u00eda Medieval y de la Edad Moderna aunando\u2026 <span class=\"read-more\"><a href=\"https:\/\/iestrevenque.es\/sitio\/2020\/01\/22\/monumai-fusion-entre-historia-del-arte-matematica-e-inteligencia-artificial\/\">Leer m\u00e1s &raquo;<\/a><\/span><\/p>\n","protected":false},"author":3,"featured_media":1495,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[9],"tags":[],"class_list":["post-3966","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-extraescolares-y-complementarias"],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pa47Ce-11Y","jetpack_featured_media_url":"https:\/\/i0.wp.com\/iestrevenque.es\/sitio\/wp-content\/uploads\/2019\/01\/512x512bb-e1548283979533.jpg?fit=148%2C145&ssl=1","_links":{"self":[{"href":"https:\/\/iestrevenque.es\/sitio\/wp-json\/wp\/v2\/posts\/3966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iestrevenque.es\/sitio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iestrevenque.es\/sitio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iestrevenque.es\/sitio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/iestrevenque.es\/sitio\/wp-json\/wp\/v2\/comments?post=3966"}],"version-history":[{"count":2,"href":"https:\/\/iestrevenque.es\/sitio\/wp-json\/wp\/v2\/posts\/3966\/revisions"}],"predecessor-version":[{"id":3994,"href":"https:\/\/iestrevenque.es\/sitio\/wp-json\/wp\/v2\/posts\/3966\/revisions\/3994"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iestrevenque.es\/sitio\/wp-json\/wp\/v2\/media\/1495"}],"wp:attachment":[{"href":"https:\/\/iestrevenque.es\/sitio\/wp-json\/wp\/v2\/media?parent=3966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iestrevenque.es\/sitio\/wp-json\/wp\/v2\/categories?post=3966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iestrevenque.es\/sitio\/wp-json\/wp\/v2\/tags?post=3966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}